

{"id":883,"date":"2019-09-30T03:48:56","date_gmt":"2019-09-30T03:48:56","guid":{"rendered":"https:\/\/www.leawo.org\/fr\/frguides\/?p=883"},"modified":"2019-09-30T03:48:59","modified_gmt":"2019-09-30T03:48:59","slug":"conversion-de-blu-ray-en-video-mkv-3d-en-anaglyphe","status":"publish","type":"post","link":"https:\/\/www.leawo.org\/fr\/frguides\/conversion-de-blu-ray-en-video-mkv-3d-en-anaglyphe.html","title":{"rendered":"Conversion de Blu-Ray en Vid\u00e9o MKV 3D en Anaglyphe"},"content":{"rendered":"<p>La technologie 3D arrive \u00e0 maturit\u00e9 de nos jours. Les amateurs de cin\u00e9ma aimeraient cr\u00e9er des films 3D \u00e0 partir de films 2D originaux. Parmi de nombreux types 3D, l'anaglyphe et la 3D c\u00f4te \u00e0 c\u00f4te sont deux types courants. Cet article utilise l'anaglyphe 3D comme exemple pour montrer aux fans de films 3D comment convertir un Blu-ray 2D en MKV en 3D anaglyphe.<\/p>\n<div class=\"anchor-list-dark\">\n<ul>\n<li> <a href=\"#part1\">Partie 1 : \u00c9chauffement pour l'Anaglyphe 3D<\/a><\/li>\n<li> <a href=\"#part2\">Partie 2 : Conversion de Blu-ray 2D en MKV 3D Anaglyphe<\/a><\/li>\n<li> <a href=\"#part3\">Partie 3 : D\u00e9monstration Vid\u00e9o de la Conversion de Blu-ray 2D en Vid\u00e9o 3D<\/a><\/li>\n<\/ul>\n<\/div>\n<h2 class=\"wp-part pl20 mt10\" id=\"part1\">Partie 1 : \u00c9chauffement pour l'Anaglyphe 3D<\/h2>\n<p>L'anaglyph 3D code l'image de chaque \u0153il en utilisant des filtres de couleurs oppos\u00e9es, g\u00e9n\u00e9ralement le rouge et le cyan. Les deux images filtr\u00e9es diff\u00e9remment garantissent des informations lumineuses diff\u00e9rentes sur chaque \u0153il, trompant ainsi votre perception habituelle et provoquant un saut de l'avant-plan vers vous. Lorsqu'elles sont visionn\u00e9es \u00e0 travers les \u00ab les lunettes anaglyphes \u00bb \u00ab \u00e0 code de couleur \u00bb, chacune des deux images atteint l'\u0153il auquel elle est destin\u00e9e, r\u00e9v\u00e9lant ainsi une image st\u00e9r\u00e9oscopique int\u00e9gr\u00e9e. Le cortex visuel du cerveau le fusionne en une perception d'une sc\u00e8ne ou d'une composition en trois dimensions.<\/p>\n<div class=\"\"><a onclick=\"return hs.expand(this)\" href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2014\/11\/3D-anaglyph-Paris-tour-eiffel.jpg\"><img decoding=\"async\" class=\"img_big lazyload\" title=\"3D-anaglyph-Paris-tour-eiffel\" alt=\"3D-anaglyph-Paris-tour-eiffel\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2014\/11\/3D-anaglyph-Paris-tour-eiffel.jpg\" width=\"650\" height=\"480\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 650px; --smush-placeholder-aspect-ratio: 650\/480;\"><\/a><\/div>\n<h2 class=\"wp-part pl20 mt10\" id=\"part2\">Partie 2 : Conversion de Blu-ray 2D en MKV 3D Anaglyphe<\/h2>\n<p><a href=\"https:\/\/www.leawo.org\/blu-ray-ripper\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Extracteur de Blu-ray de Leawo<\/strong><\/a> fonctionne non seulement comme convertisseur Blu-ray pour extraire et convertir des films Blu-ray en vid\u00e9os et extraire des fichiers audio \u00e0 partif de films Blu-ray afin de les enregistrer dans diff\u00e9rents formats, mais \u00e9galement en tant que cr\u00e9ateur de films 3D pouvant cr\u00e9er des films 3D \u00e0 partir de films Blu-ray 2D courants avec diff\u00e9rents effets 3D. Dot\u00e9 d'un convertisseur 2D en 3D \u00e0 l'int\u00e9rieur, Extracteur de Blu-ray de Leawo pourrait vous aider \u00e0 convertir facilement des Blu-ray 2D en vid\u00e9o MKV 3D sur votre PC en effet 3D c\u00f4te \u00e0 c\u00f4te ou anaglyphe. Les \u00e9tapes ci-dessous vous montrent comment convertir un Blu-ray 2D en MKV 3D anaglyphe.<\/p>\n<p><strong>Guide sur la conversion de Blu-ray 2D en vid\u00e9o MKV 3D anaglyphe :<\/strong><\/p>\n<p>\u00c9tape 1 : Installez l'Extracteur de Blu-ray de Leawo sur votre ordinateur, puis lancez-le. Cet Extracteur de Blu-ray fonctionne sur Windows Vista et les versions ult\u00e9rieures. Si vous souhaitez convertir un 2D Blu-ray en MKV 3D anaglyphe sur Mac, essayez l'Extracteur de Blu-ray de Leawo pour Mac.<\/p>\n<p><a href=\"https:\/\/www.leawo.org\/fr\/downloads\/blu-ray-ripper.html\"><img decoding=\"async\" data-src=\"\/images\/icon\/Trial_win1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a>&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/www.leawo.org\/fr\/downloads\/blu-ray-ripper-mac.html\"><img decoding=\"async\" data-src=\"\/images\/icon\/Trial_mac1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a><\/p>\n<p>\u00c9tape 2 : Ajoutez des films Blu-ray<\/p>\n<p>Faites glisser le film Blu-ray sources ou cliquez sur le bouton \u00ab Add Blu-ray\/DVD \u00bb (Ajouter Blu-ray \/ DVD) pour le charger. Vous pouvez charger le contenu Blu-ray souhait\u00e9 en s\u00e9lectionnant le mode de chargement \u00e0 partir de \u00ab Full Movie \u00bb (Film Complet), \u00ab Main Movie \u00bb (Film Principal) ou \u00ab Custom Mode \u00bb (Mode Personnalis\u00e9). Une fois charg\u00e9, vous pouvez s\u00e9lectionner les sous-titres et les pistes audio.<\/p>\n<p><a onclick=\"return hs.expand(this)\" href=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-import.jpg\"><img decoding=\"async\" data-src=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-import-t.jpg\" title=\"load source 2D Blu-ray\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a><\/p>\n<p>\u00c9tape 3 : D\u00e9finir l'effet 3D<\/p>\n<p>Faites un clic droit sur le titre Blu-ray dans le panneau de la liste de traitement gauche, puis s\u00e9lectionnez l'option \u00ab Edit \u00bb (Modifier) pour acc\u00e9der au panneau de montage vid\u00e9o. Ouvrez l'onglet \u00ab 3D \u00bb, passez le bouton \u00ab 3D Mode \u00bb (Mode 3D) au vert, puis s\u00e9lectionnez un \u00ab Red\/Cyan \u00bb (Rouge \/ Cyan), soit anaglyphe, comme l'effet 3D de sortie. La profondeur 3D est r\u00e9glable entre -50 et 50. Vous pouvez obtenir un aper\u00e7u instantan\u00e9 via le lecteur int\u00e9gr\u00e9.<\/p>\n<p><strong>Remarque<\/strong> : si vous souhaitez produire une vid\u00e9o 3D c\u00f4te \u00e0 c\u00f4te, choisissez \u00ab Side by Side \u00bb (C\u00f4te \u00e0 C\u00f4te) en mode 3D.<\/p>\n<p><a onclick=\"return hs.expand(this)\" href=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-3d.jpg\"><img decoding=\"async\" data-src=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-3d-t.jpg\" title=\"3D mode setting\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a><\/p>\n<p>\u00c9tape 4 : D\u00e9finir le profil de sortie<\/p>\n<p>Pour convertir Blu-ray en vid\u00e9o MKV 3D, vous devez d\u00e9finir MKV comme format de sortie. Cliquez sur la liste d\u00e9roulante (\u00ab Vid\u00e9o MP4 \u00bb par d\u00e9faut) \u00e0 c\u00f4t\u00e9 du bouton \u00ab Add Blu-ray\/DVD \u00bb (Ajouter un Blu-ray \/ DVD), puis s\u00e9lectionnez l'option \u00ab Change &gt; Format \u00bb (Modifier &gt; Format) pour d\u00e9finir MKV comme format de sortie.<\/p>\n<p><a onclick=\"return hs.expand(this)\" href=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-profile.jpg\"><img decoding=\"async\" data-src=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-profile-t.jpg\" title=\"output format setting\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a><\/p>\n<p>Pour une utilisation avanc\u00e9e, vous pouvez personnaliser les param\u00e8tres vid\u00e9o et audio du profil de sortie en cliquant sur la m\u00eame liste d\u00e9roulante et en choisissant l'option \u00ab Edit \u00bb (Modifier) pour acc\u00e9der au panneau \u00ab Profile Settings \u00bb (Param\u00e8tres du Profil). Vous pouvez modifier le codec vid\u00e9o, le codec audio, le d\u00e9bit binaire, le format de l'image, la r\u00e9solution, la fr\u00e9quence d'images, le canal et d'autres param\u00e8tres.<\/p>\n<p><a onclick=\"return hs.expand(this)\" href=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-settings.jpg\"><img decoding=\"async\" data-src=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-settings-t.jpg\" title=\"parameters setting\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a><\/p>\n<p>\u00c9tape 5 : D\u00e9marrez la conversion de Blu-ray 2D en vid\u00e9o MKV 3D<\/p>\n<p>Enfin, cliquez sur le gros bouton vert \u00ab Convert \u00bb (Convertir), configurez le r\u00e9pertoire \u00ab Save to \u00bb (Enregistrer dans), puis cliquez sur l'autre bouton \u00ab Convert \u00bb (Convertir) au bas de la barre lat\u00e9rale d\u00e9roulante. Ce convertisseur de Blu-ray 2D en vid\u00e9o MKV 3D lancerait imm\u00e9diatement la conversion de Blu-ray 2D en vid\u00e9o MKV 3D.<\/p>\n<p><a onclick=\"return hs.expand(this)\" href=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-convert.jpg\"><img decoding=\"async\" data-src=\"\/images\/tutorial\/blu-ray-ripper\/blu-ray-ripper-convert-t.jpg\" title=\"start to convert\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a><\/p>\n<p>Remarque : Pour convertir des vid\u00e9os 2D en vid\u00e9os 3D courantes, utilisez le <a href=\"https:\/\/www.leawo.org\/fr\/video-converter\/\" target=\"_blank\" rel=\"noopener noreferrer\">Convertisseur de vid\u00e9o de Leawo<\/a>.<\/p>\n<h2 class=\"wp-part pl20 mt10\" id=\"part3\">Partie 3 : D\u00e9monstration Vid\u00e9o de la Conversion de Blu-ray 2D en Vid\u00e9o 3D<\/h2>\n<p>Les apprenants visuels peuvent avoir du mal \u00e0 comprendre le tutoriel de texte. Ici, une vid\u00e9o de d\u00e9monstration de l'utilisation de l'Extracteur de Blu-ray de Leawo est pr\u00e9sent\u00e9e. Cliquez dessus pour mieux comprendre comment convertir un Blu-ray en MKV 3D anaglyphe.<\/p>\n<p><iframe width=\"650\" height=\"400\" data-src=\"https:\/\/www.youtube.com\/embed\/ZnUogZAY4fk\" frameborder=\"0\" allowfullscreen=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La technologie 3D arrive \u00e0 maturit\u00e9 de nos jours. Les amateurs de cin\u00e9ma aimeraient cr\u00e9er des films 3D \u00e0 partir de films 2D originaux. Parmi de nombreux types 3D, l'anaglyphe et la 3D c\u00f4te \u00e0 c\u00f4te sont deux types courants. Cet article utilise l'anaglyphe 3D comme exemple pour montrer aux fans de films 3D comment [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,23,40],"tags":[198],"class_list":["post-883","post","type-post","status-publish","format-standard","hentry","category-blu-ray-to-3d","category-blu-ray-to-video-formats","category-convert-blu-ray","tag-blu-ray-ripper"],"aioseo_notices":[],"views":3381,"_links":{"self":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/comments?post=883"}],"version-history":[{"count":3,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/883\/revisions"}],"predecessor-version":[{"id":886,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/883\/revisions\/886"}],"wp:attachment":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/media?parent=883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/categories?post=883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/tags?post=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}