

{"id":3511,"date":"2020-05-21T03:07:20","date_gmt":"2020-05-21T03:07:20","guid":{"rendered":"https:\/\/www.leawo.org\/fr\/frguides\/?p=3511"},"modified":"2020-05-21T03:07:20","modified_gmt":"2020-05-21T03:07:20","slug":"comment-resoudre-le-probleme-selon-lequel-liphone-ne-sallume-pas","status":"publish","type":"post","link":"https:\/\/www.leawo.org\/fr\/frguides\/comment-resoudre-le-probleme-selon-lequel-liphone-ne-sallume-pas.html","title":{"rendered":"Comment r\u00e9soudre le probl\u00e8me selon lequel l'iPhone ne s'allume pas"},"content":{"rendered":"<p>Vous venez d'acheter un nouvel iPhone 5s, mais votre iPhone 5s ne s'allume pas, vous avez soudainement senti que c'\u00e9tait la fin du monde. Parfois, ce n'est pas grave que votre iPhone 5s ne s'allume pas, car il existe de nombreuses astuces pour r\u00e9soudre le probl\u00e8me \u00ab L'iPhone 5s \/ 5c \/ 4 \/ 4s ne s'allume pas \u00bb.<\/p>\n<div class=\"anchor-list-dark\">\n<ul class=\"pl40\">\n<li><a href=\"#part1\">Partie 1 : Pourquoi mon iPhone ne s'allume-t-il pas ?<\/a><\/li>\n<li><a href=\"#part2\">Partie 2 : Les solutions pour r\u00e9parer l'iPhone incapable de s'allumer<\/a><\/li>\n<li><a href=\"#part3\">Partie 3 : Comment sauvegarder des donn\u00e9es de l'iPhone vers l'ordinateur \u00e0 l'aide d'iTransfer de Leawo<\/a><\/li>\n<\/ul>\n<\/div>\n<h2 id=\"part1\" class=\"wp-part\"><strong>Partie 1 : Pourquoi mon iPhone ne s'allume-t-il pas ?<\/strong><\/h2>\n<p>Si votre iPhone ne s'allume pas, cela peut \u00eatre d\u00fb \u00e0 diverses raisons, telles que des plantages logiciels, des probl\u00e8mes mat\u00e9riels, etc. Permettez-moi de vous expliquer les raisons pour lesquelles mon iPhone 5s ne s'allume pas.<\/p>\n<ol class=\"pl40\">\n<li>Votre iPhone se d\u00e9charge. C'est peut-\u00eatre la premi\u00e8re raison \u00e0 laquelle nous avons pens\u00e9 lorsque notre iPhone ne s'allume pas. Pour v\u00e9rifier si votre smartphone est d\u00e9charg\u00e9 ou non, vous pouvez recharger votre iPhone.\n<\/li>\n<li>Votre iPhone a rencontr\u00e9 un plantage logiciel. Le plantage du logiciel entra\u00eenera de nombreux probl\u00e8mes, tels que \u00ab l'iPhone ne s'allumera pas \u00bb, aucun r\u00e9seau, etc. Lorsque votre iPhone ne s'allume pas, vous pourriez envisager cette raison.\n<\/li>\n<li>Certaines applications ne sont pas compatibles avec votre iPhone. Parfois, l'incompatibilit\u00e9 de ces applications avec l'iPhone peut \u00e9galement provoquer \u00ab l'iPhone ne s'allume pas \u00bb.\n<\/li>\n<li>Un probl\u00e8me mat\u00e9riel se produit sur l'iPhone. S'il s'agit d'un probl\u00e8me mat\u00e9riel, ce sera un peu d\u00e9licat. Vous devez vous rendre dans un atelier de r\u00e9paration pour r\u00e9parer votre iPhone.\n<\/li>\n<li>Le d\u00e9bridage de l'iPhone. Lorsque vous cr\u00e9ez un jailbreak sur iPhone, cela peut parfois provoquer \u00ab l'iPhone ne s'allume pas \u00bb.\n<\/li>\n<\/ol>\n<h2 id=\"part2\" class=\"wp-part\"><strong>Partie 2 : Les solutions pour r\u00e9parer l'iPhone incapable de s'allumer <\/strong><\/h2>\n<p>Lorsque l'\u00e9cran de votre iPhone devient noir et ne s'allume pas, vous pouvez suivre les m\u00e9thodes de base simples ci-dessous pour r\u00e9soudre le probl\u00e8me \u00ab Pourquoi mon iPhone 5s ne s'allume pas \u00bb ou \u00ab Pourquoi mon iPhone 5c ne s'allume pas \u00bb.<\/p>\n<h3 class=\"wp-h3\"><strong>1. Chargez votre iPhone<\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on1.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on1.jpg\" title=\"Charge your iPhone\" alt=\"Charge your iPhone\" width=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a> <\/div>\n<p>Vous pensez peut-\u00eatre qu'il est n\u00e9gligeable de r\u00e9parer \u00ab l'iPhone ne s'allume pas \u00bb en chargeant l'iPhone. En fait, cette m\u00e9thode aide beaucoup. Pour v\u00e9rifier si le probl\u00e8me est d\u00fb \u00e0 cette raison, vous pouvez brancher votre iPhone au chargeur ou \u00e0 l'ordinateur. Apr\u00e8s avoir charg\u00e9 pendant un certain temps, appuyez et maintenez le bouton marche \/ arr\u00eat pour rallumer l'iPhone.\n<\/p>\n<p>Remarques : branchez l'iPhone \u00e0 une alimentation USB haute puissance, telle qu'un chargeur d'alimentation. <\/p>\n<h3 class=\"wp-h3\"><strong>2. Red\u00e9marrez l'iPhone<\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on2.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on2.jpg\" title=\"Restart iPhone\" alt=\"Restart iPhone\" width=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a> <\/div>\n<p>Pour red\u00e9marrer l'iPhone, veuillez suivre ces \u00e9tapes ci-dessous :<\/p>\n<ol class=\"pl40\">\n<li>Appuyez et maintenez enfonc\u00e9 le bouton \u00ab veille \/ r\u00e9veil \u00bb et le bouton d'accueil en m\u00eame temps pendant 10 secondes.\n<\/li>\n<li>Un logo Apple s'affiche, ce qui signifie que vous avez red\u00e9marr\u00e9 l'iPhone avec succ\u00e8s.<\/li>\n<\/ol>\n<p>Ou :<\/p>\n<ol class=\"pl40\">\n<li>Appuyez et maintenez enfonc\u00e9 le bouton marche \/ arr\u00eat en haut pendant quelques secondes. Un curseur appara\u00eetra pour vous sugg\u00e9rer de le d\u00e9sactiver.\n<\/li>\n<li>Lorsqu'il s'\u00e9teint, appuyez et maintenez \u00e0 nouveau le bouton marche \/ arr\u00eat pour red\u00e9marrer l'iPhone.<\/li>\n<\/ol>\n<h3 class=\"wp-h3\"><strong>3. R\u00e9initialisez l'iPhone<\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on3.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on3.jpg\" title=\"Reset iPhone\" alt=\"Reset iPhone\" width=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a> <\/div>\n<p>Certaines personnes pourraient penser que la r\u00e9initialisation de l'iPhone entra\u00eenera une perte de donn\u00e9es. En fait, il efface uniquement la m\u00e9moire de l'appareil. Par cons\u00e9quent, veuillez vous d\u00e9tendre et apprendre \u00e0 r\u00e9initialiser l'iPhone pour r\u00e9soudre le probl\u00e8me de l'iPhone qui ne s'allumera pas.<\/p>\n<ol class=\"pl40\">\n<li>Appuyez et maintenez simultan\u00e9ment le bouton marche \/ arr\u00eat et le bouton d'accueil pendant 10 secondes (appuyez et maintenez simultan\u00e9ment le bouton marche \/ arr\u00eat et le volume sur l'iPhone 7).\n<\/li>\n<li>Lorsque le curseur de fermeture appara\u00eet, maintenez enfonc\u00e9s le bouton marche \/ arr\u00eat et le bouton d'accueil.\n<\/li>\n<li>Lorsque le logo Apple appara\u00eet, rel\u00e2chez le bouton marche \/ arr\u00eat et le bouton d'accueil, puis laissez l'iPhone red\u00e9marrer.<\/li>\n<\/ol>\n<h3 class=\"wp-h3\"><strong>4. Restaurez l'iPhone aux param\u00e8tres d'usine<\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on4.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on4.jpg\" title=\"Restore iPhone to factory settings\" alt=\"Restore iPhone to factory settings\" width=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a> <\/div>\n<p>Avant de restaurer les param\u00e8tres d'usine de l'iPhone, vous devez sauvegarder toutes vos donn\u00e9es, car cette op\u00e9ration effacera toutes les donn\u00e9es et tous les param\u00e8tres de l'iPhone.<\/p>\n<ol class=\"pl40\">\n<li>Branchez l'interface du connecteur Lightning \/ Dock via le c\u00e2ble USB de l'iPhone.\n<\/li>\n<li>Appuyez et maintenez le bouton d'accueil de l'iPhone (maintenez enfonc\u00e9 le bouton de volume sur l'iPhone 7).\n<\/li>\n<li>Tout en maintenant le bouton d'accueil enfonc\u00e9, branchez l'autre extr\u00e9mit\u00e9 de l'USB sur l'ordinateur.\n<\/li>\n<li>iTunes s'ouvre, puis rel\u00e2chez le bouton d'accueil. Vous pouvez maintenant restaurer votre iPhone aux param\u00e8tres d'usine.<\/li>\n<\/ol>\n<h3 class=\"wp-h3\"><strong>5. Mettez l'iPhone en mode DFU<\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on5.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/solutions-to-iPhone-wont-turn-on5.jpg\" title=\"Put iPhone into DFU mode\" alt=\"Put iPhone into DFU mode\" width=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a> <\/div>\n<p>Parfois, la raison pour laquelle votre iPhone ne s'allume pas est que vous avez jailbreak\u00e9 votre iPhone ou mis \u00e0 jour le syst\u00e8me en cas de batterie faible. \u00c0 ce stade, vous pouvez mettre l'iPhone en mode DFU :<\/p>\n<ol class=\"pl40\">\n<li>Connectez l'iPhone \u00e0 l'ordinateur, maintenez enfonc\u00e9 le bouton marche \/ arr\u00eat pendant 3 secondes, puis rel\u00e2chez le bouton.\n<\/li>\n<li>Appuyez et maintenez simultan\u00e9ment le bouton marche \/ arr\u00eat et le bouton d'accueil (maintenez enfonc\u00e9 le bouton de r\u00e9duction du volume sur l'iPhone 7) pendant 10 secondes.\n<\/li>\n<li>Rel\u00e2chez le bouton marche \/ arr\u00eat et maintenez enfonc\u00e9 le bouton d'accueil pendant 5 secondes. Lorsque l'iPhone devient noir sans aucune r\u00e9ponse, vous mettez l'iPhone en mode DFU. Suivez ensuite les instructions \u00e0 l'\u00e9cran.<\/li>\n<\/ol>\n<h2 class=\"wp-part\" id=\"part3\"><strong>Partie 3 : Comment sauvegarder des donn\u00e9es de l'iPhone vers l'ordinateur \u00e0 l'aide d'iTransfer de Leawo<\/strong><\/h2>\n<p>Lorsque nous r\u00e9solvons le probl\u00e8me \u00ab L'iPhone 5s ne s'allume pas \u00bb, nous devons d'abord sauvegarder les donn\u00e9es de l'iPhone. Lorsqu'il s'agit de sauvegarder des fichiers iPhone, <a href=\"https:\/\/www.leawo.org\/fr\/itransfer\/\" title=\"Leawo iPhone Transfer software\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>iTransfer de Leawo<\/strong><\/a> est le premier choix. Il permet aux utilisateurs de transf\u00e9rer des photos, des images, des vid\u00e9os, des SMS, des sonneries et des contacts entre iPhone, iPad, ordinateurs et iTunes. De cette fa\u00e7on, vous pouvez facilement sauvegarder les fichiers iPhone de l'iPhone vers l'ordinateur. Pour sauvegarder les donn\u00e9es iPhone sur un ordinateur, veuillez suivre ces \u00e9tapes ci-dessous :<\/p>\n<div class=\"container-fluid\">\n<div class=\"row\">\n<div class=\"jumbotron of myjumbotron-1\">\n<div class=\"container\">\n<div class=\"col-md-5\"> <img decoding=\"async\" data-src=\"\/images\/products-banner\/itransfer.png\" alt=\"iTransfer\" width=\"100%\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/div>\n<div class=\"col-md-7\">\n<h3><strong><a href=\"https:\/\/www.leawo.org\/fr\/itransfer\/\" title=\"Leawo iPhone Transfer software\" target=\"_blank\" rel=\"noopener noreferrer\">iTransfer de Leawo<\/a><\/strong>&nbsp;<span class=\"win_icon\"><\/span><\/h3>\n<p>\u2609 Il peut facilement transf\u00e9rer des fichiers entre des appareils iOS, iTunes et des ordinateurs.<br \/>\n\u2609 Il peut transf\u00e9rer jusqu'\u00e0 14 types de donn\u00e9es et de fichiers sans iTunes.<br \/>\n\u2609 Il prend en charge les derniers appareils iOS, tels que l'iPhone 7, l'iPhone 7 Plus, etc.<br \/>\n\u2609 Il peut lire, afficher et supprimer des donn\u00e9es et des fichiers sur des appareils iOS.<\/p>\n<p class=\"mt10\"> <a href=\"https:\/\/www.leawo.org\/downloads\/itransfer.html\"><img decoding=\"async\" alt=\"\" data-src=\"https:\/\/www.leawo.org\/images\/icon\/Trial_win1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a> <a href=\"https:\/\/www.leawo.org\/downloads\/itransfer-mac.html\"><img decoding=\"async\" alt=\"\" data-src=\"https:\/\/www.leawo.org\/images\/icon\/Trial_mac1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p>T\u00e9l\u00e9chargez et installez cet iTransfer sur votre ordinateur. Les \u00e9tapes suivantes vous montreront comment sauvegarder des donn\u00e9es et des fichiers de l'iPhone vers l'ordinateur. <\/p>\n<h3 class=\"wp-h3\"><strong>\u00c9tape 1. Ouvrez le logiciel <\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/back-up-iphone-with-leawo-itransfer1.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/back-up-iphone-with-leawo-itransfer1.jpg\" title=\"Connect iPhone with computer\" alt=\"Connect iPhone with computer\" width=\"600\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a><\/div>\n<p>Ouvrez le logiciel, puis connectez l'iPhone \u00e0 l'ordinateur via un c\u00e2ble USB. Vous pouvez voir que l'iPhone est d\u00e9tect\u00e9 dans le logiciel. Les informations d\u00e9taill\u00e9es de l'iPhone sont r\u00e9pertori\u00e9es dans la barre lat\u00e9rale gauche.<\/p>\n<h3 class=\"wp-h3\"><strong>\u00c9tape 2. S\u00e9lectionnez les donn\u00e9es et fichiers iPhone<\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/back-up-iphone-with-leawo-itransfer21.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/back-up-iphone-with-leawo-itransfer21.jpg\" title=\"Choose iPhone data and files\" alt=\"Choose iPhone data and files\" width=\"600\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a><\/div>\n<p>S\u00e9lectionnez l'une des cat\u00e9gories dans la biblioth\u00e8que iPhone, ici nous prenons le transfert de musique comme exemple. Acc\u00e9dez \u00e0 iPhone > LIBRARY (\u00ab\u00a0BIBLIOTH\u00c8QUE\u00a0\u00bb) > Music (\u00ab\u00a0Musique\u00a0\u00bb), vous pouvez voir la liste de musique affich\u00e9e dans l'interface \u00e0 droite. S\u00e9lectionnez tous les \u00e9l\u00e9ments dont vous avez besoin de sauvegarder, puis faites un clic droit pour s\u00e9lectionner Transfer to (\u00ab\u00a0Transf\u00e9rer vers\u00a0\u00bb) > My Computer (\u00ab\u00a0Poste de travail\u00a0\u00bb).<\/p>\n<h3 class=\"wp-h3\"><strong>\u00c9tape 3. Sauvegardez les donn\u00e9es et les fichiers de l'iPhone sur l'ordinateur<\/strong><\/h3>\n<div class=\"tc\"><a href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/back-up-iphone-with-leawo-itransfer31.jpg\"  onclick=\"return hs.expand(this)\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2017\/07\/back-up-iphone-with-leawo-itransfer31.jpg\" title=\"Back up iPhone data and files to computer\" alt=\"Back up iPhone data and files to computer\" width=\"600\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a><\/div>\n<p>Une bo\u00eete de dialogue pop-up vous demandera de s\u00e9lectionner le r\u00e9pertoire de sortie cible, puis cliquez sur Change (\u00ab\u00a0Changer\u00a0\u00bb) pour parcourir votre ordinateur et s\u00e9lectionnez le r\u00e9pertoire de sortie cible sur l'ordinateur. Apr\u00e8s cela, cliquez sur Transfer Now (\u00ab\u00a0Transf\u00e9rer maintenant\u00a0\u00bb) pour commencer \u00e0 sauvegarder l'iPhone sur l'ordinateur.\n<\/p>\n<p>Avec iTransfer de Leawo, vous pouvez transf\u00e9rer plusieurs donn\u00e9es et fichiers, tels que de la musique, des vid\u00e9os, des photos, etc. entre des appareils iOS, iTunes et un ordinateur. Si vous utilisez un ordinateur Mac, vous pouvez utiliser <strong><a href=\"https:\/\/www.leawo.org\/fr\/itransfer-mac\/\" title=\"Leawo iTransfer for Mac\" target=\"_blank\" rel=\"noopener noreferrer\">iTransfer de Leawo pour Mac<\/a><\/strong>.<\/p>\n<h3 class=\"wp-h3\"><strong>D\u00e9monstration vid\u00e9o sur l'utilisation d'iTransfer de Leawo<\/strong><\/h3>\n<div class=\"tc\">\n  <iframe width=\"560\" height=\"315\" data-src=\"https:\/\/www.youtube.com\/embed\/yI3_tu4xVqw\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous venez d'acheter un nouvel iPhone 5s, mais votre iPhone 5s ne s'allume pas, vous avez soudainement senti que c'\u00e9tait la fin du monde. Parfois, ce n'est pas grave que votre iPhone 5s ne s'allume pas, car il existe de nombreuses astuces pour r\u00e9soudre le probl\u00e8me \u00ab L'iPhone 5s \/ 5c \/ 4 \/ 4s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97,108,96,167,113],"tags":[200],"class_list":["post-3511","post","type-post","status-publish","format-standard","hentry","category-export-ios-data","category-backup-iphone-data","category-backup-ios-data","category-transfer-data-from-ios-to-computer","category-transfer-iphone-data","tag-itransfer"],"aioseo_notices":[],"views":852,"_links":{"self":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/3511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/comments?post=3511"}],"version-history":[{"count":2,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/3511\/revisions"}],"predecessor-version":[{"id":3513,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/3511\/revisions\/3513"}],"wp:attachment":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/media?parent=3511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/categories?post=3511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/tags?post=3511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}