

{"id":1395,"date":"2019-11-11T09:09:02","date_gmt":"2019-11-11T09:09:02","guid":{"rendered":"https:\/\/www.leawo.org\/fr\/frguides\/?p=1395"},"modified":"2019-11-11T09:09:02","modified_gmt":"2019-11-11T09:09:02","slug":"comment-transferer-des-notes-de-liphone-a-lordinateur","status":"publish","type":"post","link":"https:\/\/www.leawo.org\/fr\/frguides\/comment-transferer-des-notes-de-liphone-a-lordinateur.html","title":{"rendered":"Comment transf\u00e9rer des notes de l\u2019iPhone \u00e0 l\u2019ordinateur"},"content":{"rendered":"<p>Pour \u00e9viter d'oublier les id\u00e9es novatrices qui traversent notre esprit, nous utilisons habituellement certaines m\u00e9thodes pour nous en souvenir. Dans le pass\u00e9, nous pouvons les noter sur les cahiers, mais maintenant, nous devons simplement les taper sur l'application de notes int\u00e9gr\u00e9e dans notre iPhone. Gr\u00e2ce au d\u00e9veloppement des applications iPhone, nous sommes en mesure de prot\u00e9ger nos bonnes id\u00e9es. L'application de notes sur iPhone n'est pas seulement utilis\u00e9e pour conserver les id\u00e9es, elle peut \u00e9galement \u00eatre utilis\u00e9e comme application de liste de t\u00e2ches ou comme application de rappel, ce qui vous aidera \u00e0 vous pr\u00e9parer aux objets \u00e0 venir. Par cons\u00e9quent, les notes de l'application de notes sont tr\u00e8s importantes pour les utilisateurs d'iPhone. Cependant, apr\u00e8s la mise \u00e0 jour vers iOS 9.3.2, certains utilisateurs d'iPhone constatent que les anciennes notes de leur iPhone ont disparu et que les notes continuent d'\u00eatre effac\u00e9es de mani\u00e8re al\u00e9atoire. C'est bizarre et ennuyeux, et cela cause beaucoup de probl\u00e8mes aux utilisateurs d'iPhone. Par cons\u00e9quent, l'article ci-dessous vous pr\u00e9sentera trois m\u00e9thodes pour transf\u00e9rer des notes l'iPhone \u00e0 l'ordinateur.<\/p>\n<div class=\"anchor-list-dark\" >\n<ul>\n<li><a href=\"#part1\">M\u00e9thode 1. Utiliser iCloud pour synchroniser des notes de l'iPhone \u00e0 l'ordinateur<\/a><\/li>\n<li><a href=\"#part2\">M\u00e9thode 2. Utiliser la messagerie \u00e9lectronique pour transf\u00e9rer des notes de l'iPhone \u00e0 l'ordinateur<\/a><\/li>\n<li><a href=\"#part3\">M\u00e9thode 3. Utiliser le R\u00e9cup\u00e9rateur de donn\u00e9es iOS de Leawo pour exporter des notes de l'iPhone \u00e0 l'ordinateur<\/a><\/li>\n<\/ul>\n<\/div>\n<h2 id=\"part1\" class=\"wp-part mt10 pl20\">M\u00e9thode 1. Utiliser iCloud pour synchroniser des notes de l'iPhone \u00e0 l'ordinateur<\/h2>\n<p>Lorsque les notes sont effac\u00e9es par l'appareil, les utilisateurs essaient de trouver un moyen de synchroniser les notes de l'iPhone \u00e0 l'ordinateur pour les prot\u00e9ger, et le moyen le plus rapide devrait utiliser iCloud. Le tutoriel est pr\u00e9sent\u00e9 comme suit.<\/p>\n<div class=\"clearfix tc\">\n<div class=\"col-md-3\">\n<a onclick=\"return hs.expand(this)\" href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2013\/11\/IMG_0228.jpg\"><img decoding=\"async\" class=\"img_big lazyload\" title=\"Tap iCloud\" alt=\"Tap iCloud\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2013\/11\/IMG_0228.jpg\" width=\"100%\" height=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><br \/>\n<\/a>\n<\/div>\n<div class=\"col-md-1\"><\/div>\n<div class=\"col-md-3\">\n<a onclick=\"return hs.expand(this)\" href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2014\/03\/IMG_0231.jpg\"><img decoding=\"async\" class=\"img_big lazyload\" title=\"Tap Notes to ON\" alt=\"Tap Notes to ON\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2014\/03\/IMG_0231.jpg\" width=\"100%\" height=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><br \/>\n<\/a>\n<\/div>\n<\/div>\n<div class=\"pl20 mb10 mt10\">\n<ol>\n<li>Appuyez sur Param\u00e8tres > iCloud, puis connectez-vous \u00e0 l'iCloud avec votre identifiant Apple. Vous trouverez les cat\u00e9gories dans iCloud.<\/li>\n<li>Appuyez sur \u00ab Notes \u00bb sur Allum\u00e9, puis iCloud les t\u00e9l\u00e9chargera automatiquement sur le service cloud.<\/li>\n<li>Installez iCloud sur votre PC et entrez le m\u00eame identifiant Apple pour le saisir, puis vous pourrez obtenir les notes sur votre ordinateur.<\/li>\n<\/ol>\n<\/div>\n<p>Cela peut \u00eatre consid\u00e9r\u00e9 comme le moyen le plus rapide de transf\u00e9rer des notes de l'iPhone vers un ordinateur. Si vous souhaitez uniquement utiliser le service fourni par Apple, iCloud sera le meilleur choix.<\/p>\n<h2 id=\"part2\" class=\"wp-part pl20 mt10\">M\u00e9thode 2. Utiliser la messagerie \u00e9lectronique pour transf\u00e9rer des notes de l'iPhone \u00e0 l'ordinateur<\/h2>\n<p>Vous pouvez \u00e9galement utiliser certains services de messagerie pour accomplir la t\u00e2che. Par exemple, vous pouvez utiliser iTunes pour synchroniser des notes de l'iPhone \u00e0 l'ordinateur avec Outlook. Le guide sera pr\u00e9sent\u00e9 comme suit.<br \/>\n<a onclick=\"return hs.expand(this)\" href=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2014\/03\/sync-notes-iphone.jpg\"><img decoding=\"async\" class=\"img_big lazyload\" title=\"sync iPhone notes with Outlook\" alt=\"sync iPhone notes with Outlook\" data-src=\"https:\/\/www.leawo.org\/tutorial\/wp-content\/uploads\/2014\/03\/sync-notes-iphone.jpg\" width=\"650\" height=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><br \/>\n<\/a><\/p>\n<p>1. Branchez l'iPhone \u00e0 l'ordinateur via le c\u00e2ble USB et iTunes se lancera. Sinon, vous devez d\u00e9marrer manuellement iTunes.<br \/>\n  2. Cliquez sur le nom de votre iPhone dans la barre lat\u00e9rale gauche, puis choisissez \u00ab Info \u00bb dans le panneau de r\u00e9sum\u00e9 situ\u00e9 dans la partie droite de la fen\u00eatre. Cochez \u00ab Synchroniser des Notes \u00bb et s\u00e9lectionnez Outlook dans le menu d\u00e9roulant. Cliquez sur \u00ab Appliquer \u00bb pour lancer la synchronisation des notes de l'iPhone avec Outlook.<br \/>\n 3. Une fois le processus de synchronisation termin\u00e9, vous constaterez que les notes sont enregistr\u00e9es dans le dossier \u00ab Rappels \u00bb de votre compte Outlook et que vous pouvez les visualiser sans effort.<\/p>\n<p>L'utilisation de la messagerie \u00e9lectronique pour transf\u00e9rer des notes d'un iPhone \u00e0 un ordinateur n'est pas difficile et facile \u00e0 effectuer. Outre ces deux m\u00e9thodes, vous pouvez \u00e9galement utiliser un logiciel de <a href=\"https:\/\/www.leawo.org\/fr\/ios-data-recovery\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>r\u00e9cup\u00e9ration de donn\u00e9es pour iPhone<\/strong><\/a> pour terminer le transfert des notes sur votre iPhone. Le R\u00e9cup\u00e9rateur de donn\u00e9es iOS de Leawo est l'un des meilleurs logiciels de r\u00e9cup\u00e9ration de donn\u00e9es pour iPad \/ iPod touch \/ iPhone, et il est tr\u00e8s utile \u00e0 cet \u00e9gard.<\/p>\n<h2 id=\"part3\" class=\"wp-part pl20 mt10\">M\u00e9thode 3. Utiliser le R\u00e9cup\u00e9rateur de donn\u00e9es iOS de Leawo pour exporter des notes de l'iPhone \u00e0 l'ordinateur<\/h2>\n<p>Le R\u00e9cup\u00e9rateur de donn\u00e9es iOS de Leawo est utilis\u00e9 pour r\u00e9cup\u00e9rer des fichiers supprim\u00e9s ou perdus \u00e0 partir d'appareils iOS et des sauvegardes iTunes. Si vous souhaitez transf\u00e9rer des notes d'un iPhone \u00e0 un ordinateur, vous disposez de deux m\u00e9thodes : extraire des notes \u00e0 partir de la sauvegarde d'un iPhone et transf\u00e9rer directement d'un iPhone \u00e0 un autre. Les instructions suivantes vous montreront comment transf\u00e9rer des notes de l'iPhone \u00e0 l'ordinateur avec le R\u00e9cup\u00e9rateur de donn\u00e9es iOS de Leawo. Vous pouvez \u00e9galement t\u00e9l\u00e9charger gratuitement le logiciel pour l'essayer. Notez que la version d'essai s'arr\u00eate \u00e0 la fen\u00eatre d'aper\u00e7u.<\/p>\n<div class=\"clearfix tc mb10\">\n<div class=\"col-md-2\"><\/div>\n<div class=\"col-md-3\">\n<a href=\"https:\/\/www.leawo.org\/downloads\/ios-data-recovery.html\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/images\/icon\/Trial_win.png\" width=\"208\" alt=\"Download Windows Version\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a>\n<\/div>\n<div class=\"col-md-1\"><\/div>\n<div class=\"col-md-3\">\n<a href=\"https:\/\/www.leawo.org\/downloads\/ios-data-recovery-mac.html\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" data-src=\"https:\/\/www.leawo.org\/images\/icon\/Trial_mac.png\" width=\"208\" alt=\"Download Mac Version\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/a>\n<\/div>\n<\/div>\n<p>1. Connectez l'iPhone \u00e0 l'ordinateur avec le c\u00e2ble USB et lancez le R\u00e9cup\u00e9rateur de donn\u00e9es iOS de Leawo. Le logiciel reconna\u00eetra votre iPhone et affichera un bouton \u00ab D\u00e9marrer \u00bb au milieu de la fen\u00eatre. Cliquez sur le bouton de d\u00e9marrage, puis le logiciel analysera votre iPhone. <\/p>\n<p><a onclick=\"return hs.expand(this)\" href=\"https:\/\/www.leawo.org\/images\/tutorial\/ios-data-recovery\/ios-data-recovery-recover-from-device-scan.jpg\"><img decoding=\"async\" class=\"img_big lazyload\" title=\"Analyze iPhone\" alt=\"Analyze iPhone\" data-src=\"https:\/\/www.leawo.org\/images\/tutorial\/ios-data-recovery\/ios-data-recovery-recover-from-device-scan.jpg\" width=\"650\" height=\"385\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 650px; --smush-placeholder-aspect-ratio: 650\/385;\" \/><\/a><\/p>\n<p>2. Apr\u00e8s l'analyse de votre iPhone, le logiciel scannera le contenu de votre iPhone et affichera 12 cat\u00e9gories dans la barre lat\u00e9rale gauche. Lorsque l'analyse est termin\u00e9e, choisissez \u00ab Notes \u00bb, v\u00e9rifiez les \u00e9l\u00e9ments dont vous avez besoin, puis cliquez sur \u00ab R\u00e9cup\u00e9rer \u00bb en bas \u00e0 droite de la fen\u00eatre. <\/p>\n<p><a onclick=\"return hs.expand(this)\" href=\"https:\/\/www.leawo.org\/images\/tutorial\/ios-data-recovery\/ios-data-recovery-recover-from-ipad-preview-notes.jpg\"><img decoding=\"async\" class=\"img_big lazyload\" title=\"Preview and Select Notes\" alt=\"Preview and Select Notes\" data-src=\"https:\/\/www.leawo.org\/images\/tutorial\/ios-data-recovery\/ios-data-recovery-recover-from-ipad-preview-notes.jpg\" width=\"650\" height=\"385\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 650px; --smush-placeholder-aspect-ratio: 650\/385;\" \/><\/a>  <\/p>\n<p>3. Cliquez sur \u00ab Ouvrir \u00bb dans la bo\u00eete de dialogue, puis choisissez un dossier sur votre ordinateur pour enregistrer les notes export\u00e9es. Cliquez ensuite sur \u00ab Commencer \u00bb pour exporter les notes de l'iPhone vers l'ordinateur.\n  <\/p>\n<p>  <a onclick=\"return hs.expand(this)\" href=\"https:\/\/www.leawo.org\/images\/tutorial\/ios-data-recovery\/ios-data-recovery-recover-from-device-output-notes.jpg\"><img decoding=\"async\" class=\"img_big lazyload\" title=\"Choose Target Folder\" alt=\"Choose Target Folder\" data-src=\"https:\/\/www.leawo.org\/images\/tutorial\/ios-data-recovery\/ios-data-recovery-recover-from-device-output-notes.jpg\" width=\"650\" height=\"385\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 650px; --smush-placeholder-aspect-ratio: 650\/385;\" \/><\/a><\/p>\n<p> Lorsque le processus d'extraction ou de transfert est termin\u00e9, vous obtenez les fichiers export\u00e9s dans le dossier cible. Les notes export\u00e9es seront sauvegard\u00e9es sous forme de fichier HTML et pourront \u00eatre visualis\u00e9es avec le navigateur Internet. La fonction principale du R\u00e9cup\u00e9rateur de donn\u00e9es iOS de Leawo consiste \u00e0 r\u00e9cup\u00e9rer des fichiers supprim\u00e9s \u00e0 partir d'appareils iOS ou de sauvegardes. Par exemple, vous pouvez <a href=\"https:\/\/www.leawo.org\/tutorial\/ipad-data-recovery-recover-deleted-imessages-from-ipad.html\" target=\"_blank\" rel=\"noopener noreferrer\">r\u00e9cup\u00e9rer des iMessages supprim\u00e9s \u00e0 partir de l'iPad<\/a>. Si vous \u00eates int\u00e9ress\u00e9 par ce logiciel, allez le voir !\n  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour \u00e9viter d'oublier les id\u00e9es novatrices qui traversent notre esprit, nous utilisons habituellement certaines m\u00e9thodes pour nous en souvenir. Dans le pass\u00e9, nous pouvons les noter sur les cahiers, mais maintenant, nous devons simplement les taper sur l'application de notes int\u00e9gr\u00e9e dans notre iPhone. Gr\u00e2ce au d\u00e9veloppement des applications iPhone, nous sommes en mesure de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,96,167],"tags":[207],"class_list":["post-1395","post","type-post","status-publish","format-standard","hentry","category-backup-iphone-data","category-backup-ios-data","category-transfer-data-from-ios-to-computer","tag-ios-data-recovery"],"aioseo_notices":[],"views":1125,"_links":{"self":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/1395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/comments?post=1395"}],"version-history":[{"count":2,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/1395\/revisions"}],"predecessor-version":[{"id":1397,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/posts\/1395\/revisions\/1397"}],"wp:attachment":[{"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/media?parent=1395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/categories?post=1395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leawo.org\/fr\/frguides\/wp-json\/wp\/v2\/tags?post=1395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}